{"id":2523,"date":"2023-10-13T00:00:13","date_gmt":"2023-10-13T00:00:13","guid":{"rendered":"https:\/\/aurora-records.com\/?post_type=release&#038;p=2523"},"modified":"2023-10-15T10:27:16","modified_gmt":"2023-10-15T10:27:16","slug":"may-povagu","status":"publish","type":"release","link":"https:\/\/aurora-records.com\/uk\/release\/may-povagu\/","title":{"rendered":"MAY POVAGU"},"template":"","class_list":["post-2523","release","type-release","status-publish","hentry","isotope-item"],"acf":[],"_links":{"self":[{"href":"https:\/\/aurora-records.com\/uk\/wp-json\/wp\/v2\/release\/2523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aurora-records.com\/uk\/wp-json\/wp\/v2\/release"}],"about":[{"href":"https:\/\/aurora-records.com\/uk\/wp-json\/wp\/v2\/types\/release"}],"wp:attachment":[{"href":"https:\/\/aurora-records.com\/uk\/wp-json\/wp\/v2\/media?parent=2523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}